{"id":11,"date":"2021-06-19T17:00:24","date_gmt":"2021-06-19T15:00:24","guid":{"rendered":"http:\/\/neu.simonyan-immobilien.de\/es\/?page_id=11"},"modified":"2022-05-28T12:34:34","modified_gmt":"2022-05-28T10:34:34","slug":"haeuser","status":"publish","type":"page","link":"https:\/\/simonyan-immobilien.de\/es\/immobilien\/haeuser\/","title":{"rendered":"Houses"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11\" class=\"elementor elementor-11\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-5bf2ad4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"45527\" data-id=\"5bf2ad4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e0cd08\" data-eae-slider=\"58091\" data-id=\"3e0cd08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07ab1fa elementor-widget elementor-widget-spacer\" data-id=\"07ab1fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-4ba5ec5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"90637\" data-id=\"4ba5ec5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-253a98de\" data-eae-slider=\"55751\" data-id=\"253a98de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41903b21 elementor-widget elementor-widget-text-editor\" data-id=\"41903b21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #b01613; font-size: 14pt;\"><strong>\u00bfEst\u00e1 interesado en un inmueble?<\/strong><\/span><\/h2><h3><span style=\"color: #333333; font-size: 12pt;\">No dude en ponerse en contacto con nosotros<\/span><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d2c3b4c elementor-widget elementor-widget-text-editor\" data-id=\"4d2c3b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #b01613;\"><strong>Simonyan INMOBILIARIA <\/strong><\/span><br \/><span style=\"color: #333333;\">Propietario Arman Simonyan<\/span><br \/><span style=\"color: #333333;\">Furtwangler Str. 10<\/span><br \/><span style=\"color: #333333;\">40724 Hilden \/ Alemania<br \/><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12f2adbf elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"12f2adbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+ 49 2103 99 40 480<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-fax\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+49 2103 97 880 86<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mobile-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+49 176 219 98 271<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@simonyan-immobilien.de<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4660851b\" data-eae-slider=\"14506\" data-id=\"4660851b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a2d4ae5 elementor-widget elementor-widget-text-editor\" data-id=\"7a2d4ae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"av-special-heading-tag \"><strong>NUESTRAS \u00daLTIMAS OFERTAS:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7bbdbe elementor-widget elementor-widget-jet-woo-widgets-products\" data-id=\"c7bbdbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-woo-widgets-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-woo-widgets-products jet-woo-widgets\">\n<div class=\"jet-woo-products jet-woo-products--preset-1 col-row  jet-equal-cols\">\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfEst\u00e1 interesado en un inmueble? No dude en ponerse en contacto con nosotros Simonyan INMOBILIARIA Propietario Arman SimonyanFurtwangler Str. 1040724 Hilden \/ Alemania + 49 2103 99 40 480 +49 2103 97 880 86 +49 176 219 98 271 info@simonyan-immobilien.de NUESTRAS \u00daLTIMAS OFERTAS:<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":9,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/simonyan-immobilien.de\/es\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simonyan-immobilien.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/simonyan-immobilien.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/simonyan-immobilien.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simonyan-immobilien.de\/es\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":10,"href":"https:\/\/simonyan-immobilien.de\/es\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":1386,"href":"https:\/\/simonyan-immobilien.de\/es\/wp-json\/wp\/v2\/pages\/11\/revisions\/1386"}],"up":[{"embeddable":true,"href":"https:\/\/simonyan-immobilien.de\/es\/wp-json\/wp\/v2\/pages\/9"}],"wp:attachment":[{"href":"https:\/\/simonyan-immobilien.de\/es\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}