{"id":884,"date":"2021-07-19T11:01:47","date_gmt":"2021-07-19T09:01:47","guid":{"rendered":"http:\/\/neu.simonyan-immobilien.de\/arm\/?page_id=884"},"modified":"2021-08-17T00:01:54","modified_gmt":"2021-08-16T22:01:54","slug":"wohnungen","status":"publish","type":"page","link":"https:\/\/simonyan-immobilien.de\/arm\/immobilien\/wohnungen\/","title":{"rendered":"\u0532\u0576\u0561\u056f\u0561\u0580\u0561\u0576\u0576\u0565\u0580"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"884\" class=\"elementor elementor-884\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-6a53a7c0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"83656\" data-id=\"6a53a7c0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22392f0a\" data-eae-slider=\"44760\" data-id=\"22392f0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ec0c92a elementor-widget elementor-widget-spacer\" data-id=\"7ec0c92a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-79ec116b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"55662\" data-id=\"79ec116b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-50fb9d3f\" data-eae-slider=\"10605\" data-id=\"50fb9d3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-278eaf92 elementor-widget elementor-widget-text-editor\" data-id=\"278eaf92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #b01613; font-size: 14pt;\"><strong>Sie interessieren sich f\u00fcr eine Immobilie?<\/strong><\/span><\/h2><h3><span style=\"color: #333333; font-size: 12pt;\">Wir freuen uns auf Ihre Kontaktaufnahme<\/span><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3317d454 elementor-widget elementor-widget-text-editor\" data-id=\"3317d454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #b01613;\"><strong>Simonyan Immobilien &amp; Investment<\/strong><\/span><br \/><span style=\"color: #333333;\">Inh. Arman Simonyan<\/span><br \/><span style=\"color: #333333;\">Furtw\u00e4ngler Str. 10<\/span><br \/><span style=\"color: #333333;\">40724 Hilden \/ Deutschland<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5eec82 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a5eec82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">02103 99 40 480<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-fax\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">02103 97 880 86<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mobile-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">0176 219 98 271<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@simonyan-immobilien.de\/arm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7126d7d5\" data-eae-slider=\"84855\" data-id=\"7126d7d5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4064a656 elementor-widget elementor-widget-text-editor\" data-id=\"4064a656\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"av-special-heading-tag \"><strong>UNSERE AKTUELLSTEN ANGEBOTE:&nbsp;<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sie interessieren sich f\u00fcr eine Immobilie? Wir freuen uns auf Ihre Kontaktaufnahme Simonyan Immobilien &amp; InvestmentInh. Arman SimonyanFurtw\u00e4ngler Str. 1040724 Hilden \/ Deutschland 02103 99 40 480 02103 97 880 86 0176 219 98 271 info@simonyan-immobilien.de\/arm UNSERE AKTUELLSTEN ANGEBOTE:&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":9,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-884","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/simonyan-immobilien.de\/arm\/wp-json\/wp\/v2\/pages\/884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simonyan-immobilien.de\/arm\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/simonyan-immobilien.de\/arm\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/simonyan-immobilien.de\/arm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simonyan-immobilien.de\/arm\/wp-json\/wp\/v2\/comments?post=884"}],"version-history":[{"count":10,"href":"https:\/\/simonyan-immobilien.de\/arm\/wp-json\/wp\/v2\/pages\/884\/revisions"}],"predecessor-version":[{"id":1456,"href":"https:\/\/simonyan-immobilien.de\/arm\/wp-json\/wp\/v2\/pages\/884\/revisions\/1456"}],"up":[{"embeddable":true,"href":"https:\/\/simonyan-immobilien.de\/arm\/wp-json\/wp\/v2\/pages\/9"}],"wp:attachment":[{"href":"https:\/\/simonyan-immobilien.de\/arm\/wp-json\/wp\/v2\/media?parent=884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}